{"id":26709,"date":"2019-03-26T15:43:40","date_gmt":"2019-03-26T15:43:40","guid":{"rendered":"https:\/\/hallow.com\/?page_id=26709"},"modified":"2026-07-11T19:40:50","modified_gmt":"2026-07-11T19:40:50","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/hallow.com\/es\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de Privacidad"},"content":{"rendered":"\n<p class=\"\"><strong>NOTA: Esta versi\u00f3n de la Pol\u00edtica de privacidad se public\u00f3 inicialmente el 9 de julio de 2026 y entra en vigor el 17 de julio de 2026. Se puede acceder a las versiones anteriores de nuestra Pol\u00edtica de privacidad <\/strong><a href=\"https:\/\/hallow.com\/previous-privacy-policies\/\"><strong>aqu\u00ed<\/strong><\/a><strong>.<\/strong><\/p>\n\n\n\n<p class=\"\">En Hallow damos gran importancia a la protecci\u00f3n de los datos y la privacidad. Esta Pol\u00edtica de privacidad describe c\u00f3mo recopilamos y utilizamos sus Datos personales, y lo alentamos a que la lea en su totalidad. A continuaci\u00f3n se muestra una descripci\u00f3n general de los puntos clave de nuestra pol\u00edtica y nuestras pr\u00e1cticas de privacidad:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No vendemos Datos personales (como se definen m\u00e1s adelante).\u00a0<\/li>\n\n\n\n<li>Nos encargamos de cifrar los datos personales confidenciales privados (definidos m\u00e1s adelante), como entradas de diario o reflexiones, para que solo usted tenga acceso a ese contenido.<\/li>\n\n\n\n<li>Cualquier dato anal\u00edtico de la aplicaci\u00f3n que recopilemos, con el fin de mejorar o personalizar el producto, la mensajer\u00eda y el contenido, se estudia solo a nivel agregado en toda la comunidad de Hallow (por ejemplo, qu\u00e9 sesiones son las m\u00e1s populares), a menos que sea necesario para la atenci\u00f3n a un cliente espec\u00edfico o la resoluci\u00f3n de errores.<\/li>\n\n\n\n<li>No compartimos, vendemos, alquilamos ni proporcionamos Datos personales de los usuarios a ning\u00fan agente de datos.<\/li>\n\n\n\n<li>Como es habitual para los servicios basados en la web, nos asociamos con Proveedores de servicios (por ejemplo, procesadores de pagos, proveedores de bases de datos) para apoyar a nuestros Socios anal\u00edticos y de aplicaciones para estudiar la mejor manera de mejorar nuestra Aplicaci\u00f3n (por ejemplo, qu\u00e9 sesiones son las m\u00e1s populares). Los Datos personales revelados a estos proveedores est\u00e1n cifrados y protegidos tanto en tr\u00e1nsito como en reposo.<\/li>\n\n\n\n<li>No compartimos ning\u00fan dato personal confidencial privado con ning\u00fan Socio publicitario.\u00a0<\/li>\n\n\n\n<li>No recopilamos ni solicitamos a sabiendas los datos de personas menores de 13 a\u00f1os sin obtener\u00a0 \u00a0 \u00a0 el consentimiento de acuerdo con la ley aplicable, como se describe en la secci\u00f3n \u00ab<a href=\"https:\/\/hallow.com\/privacy-policy\/%23personal-data-of-children\">Datos personales de menores<\/a>\u00bb m\u00e1s adelante, y no divulgamos a sabiendas informaci\u00f3n sobre personas menores de 13 a\u00f1os a los Socios publicitarios.<\/li>\n\n\n\n<li>Usted puede, con sujeci\u00f3n a los t\u00e9rminos de esta Pol\u00edtica de privacidad, eliminar su cuenta completa y todos los Datos personales asociados con ella en cualquier momento.<\/li>\n<\/ul>\n\n\n\n<p class=\"\">En cualquier momento, usted puede optar por no recibir cookies (excepto las funcionalmente necesarias para ejecutar el sitio) y otras tecnolog\u00edas de seguimiento, o ejercer sus otros derechos en virtud de las leyes aplicables, como ciertas leyes de privacidad estatales de los Estados Unidos o el Reglamento General de Protecci\u00f3n de Datos de la UE (el \u00abRGPD\u00bb). Por favor, lea la Pol\u00edtica de privacidad completa para obtener m\u00e1s detalles.<\/p>\n\n\n\n<p class=\"\">Su uso de nuestros Servicios est\u00e1 sujeto a nuestros <a href=\"https:\/\/hallow.com\/terms-of-service\/\">T\u00e9rminos de servicio<\/a>, que incorporan esta Pol\u00edtica de privacidad. Cualquier t\u00e9rmino que utilicemos en esta Pol\u00edtica de privacidad sin definirlo tiene las definiciones que se le dan en los T\u00e9rminos de servicio. Si hacemos cualquier cambio en la forma en que recopilamos o utilizamos sus Datos personales, le notificaremos sobre esos cambios de acuerdo con la secci\u00f3n titulada <a href=\"https:\/\/hallow.com\/privacy-policy\/%23changes-to-privacy-policy\">\u00abCambios a esta Pol\u00edtica de privacidad\u00bb<\/a> m\u00e1s adelante.&nbsp;<\/p>\n\n\n\n<p class=\"\"><strong>Al crear una cuenta, acceder a nuestros Servicios u optar por recibir comunicaciones nuestras, usted reconoce que acepta las pr\u00e1cticas y pol\u00edticas que se describen a continuaci\u00f3n, y usted acepta que recopilemos, utilicemos y divulguemos su informaci\u00f3n como se describe en esta Pol\u00edtica de privacidad.<\/strong>&nbsp;Si usted es&nbsp; &nbsp; &nbsp; un menor (como se define m\u00e1s adelante), aseg\u00farese de leer esta Pol\u00edtica de privacidad con alguno de sus padres o un tutor.<\/p>\n\n\n\n<p class=\"\"><strong>Tabla de contenido<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/hallow.com\/privacy-policy\/%23privacy-policy-covers\"><strong>Qu\u00e9 cubre esta Pol\u00edtica de privacidad<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hallow.com\/privacy-policy\/%23personal-data\"><strong>Datos personales<\/strong><\/a>\n<ol class=\"wp-block-list\">\n<li><a href=\"https:\/\/hallow.com\/privacy-policy\/%23categories-of-personal-data-we-collect\"><em>Categor\u00edas de datos personales que recopilamos<\/em><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hallow.com\/privacy-policy\/%23categories-of-sources-of-personal-data\"><em>Categor\u00edas de or\u00edgenes de datos personales<\/em><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hallow.com\/privacy-policy\/%23purposes-for-collecting-personal-data\"><em>Nuestros fines comerciales o empresariales para recopilar<\/em><\/a><a href=\"https:\/\/hallow.com\/privacy-policy\/%23purposes-for-collecting-personal-data\"><em>o divulgar<\/em><\/a><a href=\"https:\/\/hallow.com\/privacy-policy\/%23purposes-for-collecting-personal-data\"><em>datos personales<\/em><\/a><\/li>\n<\/ol>\n<\/li>\n\n\n\n<li><a href=\"https:\/\/hallow.com\/privacy-policy\/%2523data-sharing\"><strong>Divulgaci\u00f3n de datos<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hallow.com\/privacy-policy\/%23data-security-and-retention\"><strong>Seguridad y retenci\u00f3n de datos<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hallow.com\/privacy-policy\/%23personal-data-of-children\"><strong>Datos personales de <\/strong><\/a>menores<\/li>\n\n\n\n<li><a href=\"https:\/\/hallow.com\/privacy-policy\/#us-state-privacy-rights\"><strong>Derechos de privacidad estatales de los Estados Unidos<\/strong><\/a> \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/li>\n\n\n\n<li><strong>Ejercicio de sus derechos bajo las leyes de privacidad estatales de los Estados Unidos<\/strong><\/li>\n\n\n\n<li>\u00a0\u00a0 \u00a0 <a href=\"https:\/\/hallow.com\/privacy-policy\/%23gdpr\"><strong>Derechos de los sujetos de datos de la Uni\u00f3n Europea y el Reino Unido<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hallow.com\/privacy-policy\/%23brazil-data-subject-rights\"><strong>Derechos de los sujetos de datos de Brasil<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hallow.com\/privacy-policy\/%23changes-to-privacy-policy\"><strong>Cambios a esta Pol\u00edtica de privacidad<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hallow.com\/privacy-policy\/%23contact-information\"><strong>Informaci\u00f3n de contacto<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"\"><strong>1. Qu\u00e9 cubre esta Pol\u00edtica de privacidad<\/strong><\/p>\n\n\n\n<p class=\"\">Esta Pol\u00edtica de privacidad cubre c\u00f3mo tratamos los Datos personales que recopilamos cuando usted accede o utiliza nuestros Servicios. \u00abDatos personales\u00bb se refiere a cualquier informaci\u00f3n que identifique o se relacione con una persona en particular y tambi\u00e9n incluye informaci\u00f3n denominada \u00abinformaci\u00f3n de identificaci\u00f3n personal\u00bb o \u00abinformaci\u00f3n personal\u00bb en virtud de las leyes, reglas o regulaciones de privacidad de datos aplicables. Esta Pol\u00edtica de privacidad no cubre las pr\u00e1cticas de empresas que no nos pertenecen ni controlamos ni de personas que no administramos.<\/p>\n\n\n\n<p class=\"\"><strong>2. Datos personales<\/strong><\/p>\n\n\n\n<p class=\"\"><strong>Categor\u00edas de datos personales que recopilamos<\/strong><\/p>\n\n\n\n<p class=\"\">Esta secci\u00f3n detalla las categor\u00edas de Datos personales que recopilamos y hemos recopilado en los \u00faltimos 12 meses.&nbsp; &nbsp; &nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Categor\u00eda de datos personales:<\/strong><\/td><td><strong>Por qu\u00e9 recopilamos esto:<\/strong><\/td><td><strong>Ejemplos de datos personales que recopilamos:<\/strong><\/td><td><strong>Categor\u00edas de terceros con los que compartimos estos Datos personales:<\/strong><\/td><\/tr><tr><td><strong>Datos de perfil o de contacto<\/strong><\/td><td>Recopilados con el fin de crear y administrar cuentas de usuario y revelados a los Proveedores de servicios y Socios anal\u00edticos (cada uno como se define m\u00e1s adelante) para prestar y mejorar los Servicios.&nbsp; Si usted elige participar en nuestra funci\u00f3n Comunidad (como una parroquia de la que usted es miembro), usted puede optar por hacer que su nombre y su foto de perfil sean visibles para otros usuarios interesados en unirse al grupo, otros miembros del grupo y\/o el administrador del grupo relevante.<\/td><td>&#8211; Nombre<br>&#8211; Correo electr\u00f3nico<br>&#8211; N\u00famero de tel\u00e9fono &#8211; Foto asociada con su cuenta de Hallow &#8211; Suscripci\u00f3n voluntaria a SMS<\/td><td>&#8211; Proveedores de servicios<br>&#8211; Socios anal\u00edticos **<br>&#8211; Partes que usted autoriza, accede o autentica<\/td><\/tr><tr><td><strong>Datos personales confidenciales*<\/strong><\/td><td>Recopilados para proporcionarle los Servicios y revelados a los Proveedores de servicios para proporcionar nuestros Servicios (por ejemplo, el proveedor de base de datos); sin embargo, estos Datos personales est\u00e1n cifrados con cifrado est\u00e1ndar de la industria.<\/td><td>&#8211; El texto de las entradas del diario personal o reflexiones<br>&#8211; Contrase\u00f1as<br>&#8211; Aportaciones que usted puede optar por enviar al interactuar con las caracter\u00edsticas de IA<\/td><td>&#8211; Proveedores de servicios<br>&#8211; Partes que usted autoriza, accede o autentica<\/td><\/tr><tr><td><strong>An\u00e1lisis de la aplicaci\u00f3n<\/strong><\/td><td>Recopilados para fines de investigaci\u00f3n, solo a nivel agregado y an\u00f3nimo (a menos que sea necesario para una asistencia al cliente espec\u00edfica o resoluci\u00f3n de errores) y para personalizar o mejorar la mensajer\u00eda o los Servicios (por ejemplo, qu\u00e9 sesiones o funcionalidades son m\u00e1s populares) y se revelan a los Proveedores de servicios y Socios anal\u00edticos para proporcionar y mejorar nuestros Servicios.&nbsp;<\/td><td>&#8211; Solo con su consentimiento expreso para<br>hacerlo, usted puede optar por revelar informaci\u00f3n sobre sus creencias religiosas durante la incorporaci\u00f3n a una nueva cuenta o a trav\u00e9s de encuestas an\u00f3nimas y opcionales<br>&#8211; Compromiso con la funcionalidad de la aplicaci\u00f3n, incluidas las Aportaciones de IA que usted puede optar por enviar al interactuar con funciones de IA o publicaciones que usted realiza en grupos dentro de la aplicaci\u00f3n<\/td><td>&#8211; Proveedores de servicios<br>&#8211; Socios anal\u00edticos **<br>&#8211; Partes que usted autoriza, accede o autentica<\/td><\/tr><tr><td><strong>Datos de pago<\/strong><\/td><td>Nuestros proveedores de servicios de procesamiento de pagos (por ejemplo, Stripe, Apple, Google) recopilan su informaci\u00f3n de tarjeta de pago proporcionada voluntariamente para procesar su pago.&nbsp;<\/td><td>&#8211; Tipo de tarjeta de pago<br>&#8211; N\u00famero de tarjeta de cr\u00e9dito<br>&#8211; Direcci\u00f3n de facturaci\u00f3n, n\u00famero de tel\u00e9fono y correo electr\u00f3nico<br>&#8211; Historial de compras<\/td><td>\u2013 Proveedores de servicios&nbsp; &nbsp; &nbsp; &#8211; Socios de recaudaci\u00f3n de fondos para pagos de Campa\u00f1as de donaciones&nbsp; &nbsp; &nbsp;<\/td><\/tr><tr><td><strong>Datos de publicidad<\/strong><\/td><td>Recopilados y revelados a nuestros Proveedores de servicios, Socios anal\u00edticos y Socios publicitarios para ayudarnos a comercializar nuestros servicios, por ejemplo, midiendo la efectividad de nuestras campa\u00f1as publicitarias.<\/td><td>&#8211; Si el usuario comenz\u00f3 a utilizar la Aplicaci\u00f3n (es decir, si la Aplicaci\u00f3n fue instalada, se cre\u00f3 una cuenta, se inici\u00f3 la sesi\u00f3n, se inici\u00f3 la prueba o se realiz\u00f3 un pago&nbsp; &nbsp; &nbsp; \/ donaci\u00f3n)<br>&#8211; Direcci\u00f3n de correo electr\u00f3nico y nombre con hash<br>&#8211; Sistema operativo del dispositivo<br>&#8211; Identificador del dispositivo si fue concedido por el usuario (opci\u00f3n de aceptaci\u00f3n para iOS, opci\u00f3n de exclusi\u00f3n para Android)<br>&nbsp; &nbsp; &nbsp;<\/td><td>&#8211; Proveedores de servicios<br>&#8211; Socios anal\u00edticos **<br>&#8211; Socios publicitarios **<\/td><\/tr><tr><td><strong>Datos de dispositivo\/IP<\/strong><\/td><td>Recopilados autom\u00e1ticamente para ayudar con an\u00e1lisis y servicios como atenci\u00f3n al cliente y revelados a los Proveedores de servicios y Socios anal\u00edticos para proporcionar y mejorar nuestros Servicios.<\/td><td>&#8211; Direcci\u00f3n IP<br>&#8211; ID de dispositivo<br>&nbsp;&#8211; Servidor de dominio<br>&nbsp;&#8211; Sistema operativo del dispositivo<br>&nbsp;&#8211; Versi\u00f3n de la aplicaci\u00f3n<\/td><td>&#8211; Proveedores de servicios<br>&#8211; Socios anal\u00edticos**<\/td><\/tr><tr><td><strong>Datos de la libreta de direcciones<\/strong><\/td><td>Para ayudarlo, si usted lo desea, a encontrar personas que usted conozca y solo bajo su indicaci\u00f3n espec\u00edfica.<\/td><td>&#8211; Direcci\u00f3n de correo electr\u00f3nico y n\u00fameros de tel\u00e9fono con hash<\/td><td>\u2013 Proveedores de servicios<\/td><\/tr><tr><td><strong>Datos de cookies y an\u00e1lisis web<\/strong><\/td><td>Tenemos cookies en nuestro Sitio (no en la Aplicaci\u00f3n), incluidas las pertenecientes a nuestros Socios publicitarios, que recopilan y revelan Datos personales a nuestros Proveedores de servicios y Socios anal\u00edticos. Las preferencias de cookies de usuario se pueden administrar con nuestro <a href=\"https:\/\/hallow.com\/privacy-policy\/%23cookie-manager\">Administrador de cookies<\/a>. Las cookies de orientaci\u00f3n, como se definen en la Pol\u00edtica de cookies, no est\u00e1n presentes una vez que el usuario ingresa a la Aplicaci\u00f3n, por lo que las cookies de orientaci\u00f3n no capturan ninguna actividad de escucha, datos de entrada de diario ni otros datos de An\u00e1lisis de la aplicaci\u00f3n.<\/td><td>&#8211; Interacciones con p\u00e1ginas web<br>&#8211; P\u00e1gina web \/ origen de referencia a trav\u00e9s de la cual usted accedi\u00f3 a los Servicios<br>&#8211; ID de solicitud no identificables<br>&#8211; Direcci\u00f3n IP<br>&#8211; Estad\u00edsticas asociadas con la interacci\u00f3n entre el dispositivo o el navegador y los Servicios<\/td><td>&#8211; Proveedores de servicios<br>&#8211; Socios publicitarios **<br>&#8211; Socios anal\u00edticos **<\/td><\/tr><tr><td><strong>Datos demogr\u00e1ficos de los consumidores<\/strong><\/td><td>Recopilamos datos demogr\u00e1ficos con el fin de obtener el Consentimiento de los padres, para administrar nuestra funci\u00f3n Comunidad de Hallow (por ejemplo, limitar la funcionalidad de la comunidad para personas menores de cierta edad) y para personalizar la experiencia del usuario al promover y compartir publicaciones o programas de contenido espec\u00edficos (por ejemplo, el programa devocional para hombres) y revelar a los Proveedores de servicios y Socios anal\u00edticos para prestar y mejorar nuestros Servicios.<\/td><td>&#8211; Edad aproximada, fecha de nacimiento y\/o informaci\u00f3n familiar (recopilada como parte del proceso de consentimiento parental, durante la incorporaci\u00f3n o proporcionada voluntariamente)&nbsp; \u2013 G\u00e9nero (inferido en funci\u00f3n del nombre o proporcionado voluntariamente) &#8211; Los datos de actividad de la aplicaci\u00f3n recopilados pueden indicar una preferencia religiosa<\/td><td>&#8211; Proveedores de servicios<br>&#8211; Socios anal\u00edticos**<\/td><\/tr><tr><td><strong>Datos de geolocalizaci\u00f3n<\/strong><\/td><td>No recopilamos informaci\u00f3n de geolocalizaci\u00f3n precisa. Podemos utilizar su direcci\u00f3n IP para inferir su ubicaci\u00f3n imprecisa para brindarle notificaciones basadas en la ubicaci\u00f3n (por ejemplo, evento o contenido cerca de usted) o para mejorar nuestros Servicios (por ejemplo, proveedores de an\u00e1lisis, herramientas de atenci\u00f3n al cliente).&nbsp;<\/td><td>&#8211; Informaci\u00f3n de ubicaci\u00f3n basada en direcciones IP<\/td><td>&#8211; Proveedores de servicios<br>&#8211; Socios anal\u00edticos**<\/td><\/tr><tr><td><strong>Datos de salud*<\/strong><\/td><td>Revelado a servicios de terceros como Apple Health a criterio del usuario<\/td><td>&#8211; Tiempo de atenci\u00f3n plena (minutos de oraci\u00f3n)<\/td><td>\u2013 Proveedores de servicios<br>&#8211; Partes que usted autoriza, accede o autentica<\/td><\/tr><tr><td><strong>Datos de recaudaci\u00f3n de fondos<\/strong><\/td><td>Recopilamos Datos de recaudaci\u00f3n de fondos para procesar su donaci\u00f3n de una Campa\u00f1a de donaciones a un Socio de recaudaci\u00f3n de fondos, para permitir que un Socio de recaudaci\u00f3n de fondos reciba su donaci\u00f3n,&nbsp; &nbsp; &nbsp; genere un recibo y mantenga registros seg\u00fan la ley aplicable.<\/td><td>&#8211; Nombre&nbsp; &#8211; Direcci\u00f3n de correo electr\u00f3nico&nbsp; &#8211; N\u00famero de tel\u00e9fono&nbsp; &#8211; Direcci\u00f3n f\u00edsica &#8211; Monto de la donaci\u00f3n&nbsp; &#8211; Fecha de donaci\u00f3n<\/td><td>\u2013 Proveedores de servicios &#8211; Socios de recaudaci\u00f3n de fondos<\/td><\/tr><tr><td><strong>Informaci\u00f3n de contacto de ventas de cuentas empresariales<\/strong><\/td><td>Utilizamos Datos disponibles p\u00fablicamente (definidos m\u00e1s adelante) y de Proveedores para recopilar informaci\u00f3n de contacto con el fin de generar clientes potenciales para ventas de cuentas empresariales (es decir, para l\u00edderes de parroquias, escuelas y otras organizaciones)<\/td><td>&#8211; Nombre<br>&#8211; Direcci\u00f3n de correo electr\u00f3nico<br>&#8211; Puesto de trabajo<br>&#8211; N\u00famero de tel\u00e9fono<br>&#8211; Datos de perfil de LinkedIn, por ejemplo, historial laboral<br>&#8211; Direcci\u00f3n de la empresa<\/td><td>&#8211; Proveedores de servicios<br>&nbsp;&#8211; Socios&nbsp; publicitarios**<\/td><\/tr><tr><td><strong>Otra informaci\u00f3n de identificaci\u00f3n que usted elige proporcionar voluntariamente<\/strong><\/td><td>Informaci\u00f3n opcional, como datos de encuestas de suscripci\u00f3n voluntaria, que recopilamos para comprender mejor nuestros Servicios y revelar a los Proveedores de servicios y Socios anal\u00edticos para poder prestar nuestros Servicios. Si usted elige participar en nuestra funci\u00f3n Comunidad (como una parroquia de la que usted es miembro), usted puede optar por que sus interacciones dentro de la Aplicaci\u00f3n sean visibles para otros usuarios. Consulte la secci\u00f3n Comunidad de Hallow m\u00e1s adelante para obtener m\u00e1s detalles.<\/td><td>Informaci\u00f3n de identificaci\u00f3n en encuestas opcionales, correos electr\u00f3nicos, datos de entrada de IA u otras comunicaciones que usted nos env\u00eda o nos proporciona<\/td><td>&#8211; Proveedores de servicios<br>&#8211; Socios anal\u00edticos** &#8211; Partes que usted autoriza, acceden o autentican<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"\">*Estos datos se consideran \u00abconfidenciales\u00bb seg\u00fan ciertas leyes de privacidad estatales de los Estados Unidos.<\/p>\n\n\n\n<p class=\"\">** No divulgamos a sabiendas los Datos personales de ning\u00fan Ni\u00f1o menor de la edad protegida a nuestros Socios anal\u00edticos, ni divulgamos a sabiendas los Datos personales de ning\u00fan menor a nuestros Socios publicitarios. Para obtener informaci\u00f3n adicional, consulte la secci\u00f3n \u00ab<a href=\"https:\/\/hallow.com\/privacy-policy\/%23personal-data-of-children\">Datos personales de menores<\/a>\u00bb m\u00e1s adelante.<\/p>\n\n\n\n<p class=\"\"><strong>Categor\u00edas de or\u00edgenes de datos personales<\/strong><\/p>\n\n\n\n<p class=\"\">Recopilamos datos personales sobre usted de las siguientes categor\u00edas de fuentes:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>De usted<\/strong>\n<ul class=\"wp-block-list\">\n<li>Cuando usted nos proporciona dicha informaci\u00f3n directamente a nosotros.\n<ul class=\"wp-block-list\">\n<li>Cuando usted crea una cuenta o utiliza nuestras herramientas interactivas y nuestros Servicios.<\/li>\n\n\n\n<li>Cuando usted proporciona informaci\u00f3n voluntariamente en cuadros de texto de formato libre a trav\u00e9s de los Servicios, a trav\u00e9s de respuestas a formularios, encuestas, sorteos o concursos, cuando usted interact\u00faa dentro de un grupo o cuando usted participa en una Campa\u00f1a de donaci\u00f3n.<\/li>\n\n\n\n<li>Cuando usted elige interactuar con nuestras Funciones de IA, incluso enviando Entradas de IA.<\/li>\n\n\n\n<li>Cuando usted nos proporciona voluntariamente acceso a los contactos de la libreta de direcciones de su dispositivo m\u00f3vil para ayudarlo a encontrar personas que usted conoce. Cuando usted lo haga, Hallow tendr\u00e1 acceso a la informaci\u00f3n que usted ha guardado sobre sus contactos, incluyendo su direcci\u00f3n de correo electr\u00f3nico y n\u00famero de tel\u00e9fono, para determinar si est\u00e1n utilizando la Aplicaci\u00f3n o no. Si alguno de sus contactos a\u00fan no est\u00e1 utilizando la Aplicaci\u00f3n, administraremos esta informaci\u00f3n por usted de una manera que garantice que no podamos identificar esos contactos. Espec\u00edficamente, crearemos un valor hash criptogr\u00e1fico a partir de las direcciones de correo electr\u00f3nico y el n\u00famero de tel\u00e9fono de sus contactos. Cada valor hash criptogr\u00e1fico se almacena en nuestros servidores y est\u00e1 vinculado a su cuenta para que podamos conectarlo de manera m\u00e1s eficiente con estos contactos cuando se unan a Hallow. Si desea invitar a uno de sus contactos a Hallow, usted puede hacerlo envi\u00e1ndole una invitaci\u00f3n a nuestro servicio (por ejemplo, por SMS).<\/li>\n\n\n\n<li>Cuando usted nos env\u00eda un correo electr\u00f3nico o se comunica con nosotros. \u00a0<\/li>\n\n\n\n<li>Cuando usted es el padre o tutor de un ni\u00f1o y proporciona su nombre, direcci\u00f3n de correo electr\u00f3nico y otra informaci\u00f3n relacionada con el uso del Servicio por parte de un ni\u00f1o como parte del proceso de consentimiento parental. \u00a0<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Cuando usted utiliza los Servicios, dicha informaci\u00f3n se recopila autom\u00e1ticamente.\n<ul class=\"wp-block-list\">\n<li>Uso de cookies (consulte <a href=\"https:\/\/hallow.com\/cookie-policy\/\">Pol\u00edtica de Cookies<\/a> para obtener m\u00e1s informaci\u00f3n).<\/li>\n\n\n\n<li>Si usted descarga nuestra aplicaci\u00f3n m\u00f3vil o utiliza un navegador habilitado para la ubicaci\u00f3n, podemos recibir informaci\u00f3n sobre su ubicaci\u00f3n y su dispositivo m\u00f3vil, seg\u00fan corresponda.<\/li>\n\n\n\n<li>Si usted descarga e instala ciertas aplicaciones y software que ponemos a su disposici\u00f3n, podemos recibir y recopilar informaci\u00f3n transmitida desde su dispositivo inform\u00e1tico con el fin de proporcionarle los Servicios relevantes, como informaci\u00f3n sobre cu\u00e1ndo usted est\u00e1 conectado y disponible para recibir actualizaciones o notificaciones de alertas.<\/li>\n\n\n\n<li>Si usted realiza una compra o participa en una Campa\u00f1a de donaciones, podemos recibir y recopilar informaci\u00f3n sobre su compra o donaci\u00f3n, incluyendo lo que usted compr\u00f3, el monto de su pago y cualquier Informaci\u00f3n de pago necesaria para procesar su Transacci\u00f3n.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>De terceros<\/strong>\n<ul class=\"wp-block-list\">\n<li>Proveedores y datos disponibles p\u00fablicamente\n<ul class=\"wp-block-list\">\n<li>Podemos utilizar Proveedores de servicios y Socios anal\u00edticos para analizar su interacci\u00f3n, atribuci\u00f3n o compromiso con los Servicios.<\/li>\n\n\n\n<li>Utilizamos proveedores e informaci\u00f3n disponible en sitios web p\u00fablicos para obtener informaci\u00f3n de contacto y generar clientes potenciales para nuestras ventas de cuentas empresariales.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Socios publicitarios\n<ul class=\"wp-block-list\">\n<li>Recibimos informaci\u00f3n sobre usted de algunos de nuestros proveedores que nos ayudan con servicios de marketing o promocionales relacionados con la forma en que usted interact\u00faa con nuestros sitios web, aplicaciones, productos, Servicios, anuncios o comunicaciones.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Organizaciones o empresas que act\u00faan en su nombre\n<ul class=\"wp-block-list\">\n<li>A trav\u00e9s de nuestras Cuentas empresariales (es decir, para una parroquia, escuela u otra organizaci\u00f3n), podemos recibir informaci\u00f3n limitada (es decir, nombre, direcci\u00f3n de correo electr\u00f3nico) sobre usted de la Empresa con la que usted est\u00e1 afiliado para crear su cuenta para que podamos brindarle los Servicios.\u00a0<\/li>\n\n\n\n<li>Si usted es un Ni\u00f1o menor de la edad protegida, tambi\u00e9n requerimos que su padre o tutor nos proporcione su edad o fecha de nacimiento como parte del proceso de consentimiento parental.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Inicio de sesi\u00f3n de terceros\n<ul class=\"wp-block-list\">\n<li>Si usted nos proporciona las credenciales de su cuenta o de otra manera inicia sesi\u00f3n en los Servicios a trav\u00e9s de un sitio o servicio de un tercero, como Apple o Google, parte del contenido y\/o informaci\u00f3n de esas cuentas puede transmitirse a su cuenta con nosotros de acuerdo con el proceso de autorizaci\u00f3n de ese sitio y\/o la configuraci\u00f3n de su dispositivo.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"\"><strong>Nuestros fines comerciales o empresariales para recopilar o divulgar datos personales<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Proveer, personalizar y mejorar los Servicios<\/strong>\n<ul class=\"wp-block-list\">\n<li>Creaci\u00f3n y administraci\u00f3n de su cuenta u otros perfiles de usuario.<\/li>\n\n\n\n<li>Procesamiento de pedidos, donaciones u otras transacciones; facturaci\u00f3n.<\/li>\n\n\n\n<li>Brindarle los productos, servicios o informaci\u00f3n que usted solicite.<\/li>\n\n\n\n<li>Satisfacer o cumplir la raz\u00f3n por la que usted nos proporcion\u00f3 la informaci\u00f3n.<\/li>\n\n\n\n<li>Brindar soporte y asistencia para los Servicios.<\/li>\n\n\n\n<li>Mejora de los Servicios, incluyendo pruebas, investigaciones, an\u00e1lisis internos y desarrollo de productos.<\/li>\n\n\n\n<li>Personalizaci\u00f3n de los Servicios, el contenido del sitio web y las comunicaciones seg\u00fan sus preferencias.<\/li>\n\n\n\n<li>Ofrecer y desarrollar las Funciones de IA, incluyendo el procesamiento de sus Aportaciones de IA para brindarle una experiencia personalizada de HACERLO. \u00a0<\/li>\n\n\n\n<li>Realizar protecci\u00f3n contra fraudes, seguridad y depuraci\u00f3n.<\/li>\n\n\n\n<li>Llevar a cabo otros fines comerciales indicados al recopilar sus Datos personales o seg\u00fan lo establecido en las leyes de privacidad de datos aplicables, como la Ley de Privacidad del Consumidor de California , modificada por la Ley de Derechos de Privacidad de California de 2020 (\u00abCCPA\u00bb) y otras leyes de privacidad integrales estatales aplicables (colectivamente, los \u00abEstados Unidos Leyes de privacidad estatales\u00bb) como se analiza en la secci\u00f3n <a href=\"https:\/\/hallow.com\/privacy-policy\/#us-state-privacy-rights\">Derechos de privacidad estatales de los Estados Unidos<\/a> m\u00e1s adelante.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Comercializaci\u00f3n de los Servicios<\/strong>\n<ul class=\"wp-block-list\">\n<li>Comercializaci\u00f3n y venta de los Servicios.<\/li>\n\n\n\n<li>Mostrarle anuncios, incluida publicidad basada en intereses o basada en el comportamiento en l\u00ednea. Tenga en cuenta que no utilizamos ni divulgamos a sabiendas Datos personales de ning\u00fan usuario que sepamos que es un menor (definido en la secci\u00f3n <a href=\"https:\/\/hallow.com\/privacy-policy\/%23personal-data-of-children\">\u00abDatos personales de menores<\/a>\u00ab<a href=\"https:\/\/hallow.com\/privacy-policy\/%23personal-data-of-children\"> m\u00e1s adelante)<\/a> para publicidad basada en el comportamiento.<\/li>\n\n\n\n<li>Facilitar sorteos, concursos u otras promociones.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Comunicarse con usted<\/strong>\n<ul class=\"wp-block-list\">\n<li>Responder a la correspondencia que recibimos de usted, comunicarnos con usted cuando sea necesario o solicitado y enviarle informaci\u00f3n sobre Hallow o los Servicios.\u00a0<\/li>\n\n\n\n<li>Env\u00edo de correos electr\u00f3nicos y otras comunicaciones de acuerdo con sus preferencias o que creemos ser\u00e1n de su inter\u00e9s. Con sujeci\u00f3n a su derecho de exclusi\u00f3n voluntaria, podemos utilizar sus Datos de geolocalizaci\u00f3n para enviar alertas basadas en la ubicaci\u00f3n que puedan ser de su inter\u00e9s.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Cumplimiento de requisitos legales y aplicaci\u00f3n de t\u00e9rminos legales<\/strong>\n<ul class=\"wp-block-list\">\n<li>Cumplir con nuestras obligaciones legales en virtud de la ley aplicable, las regulaciones, una orden judicial u otro proceso legal, como mantener registros de las transacciones y donaciones o prevenir, detectar e investigar incidentes de seguridad y actividades potencialmente ilegales o prohibidas.<\/li>\n\n\n\n<li>Protecci\u00f3n de los derechos, la propiedad o la seguridad de los usuarios de Hallow, Hallow u otro tercero.<\/li>\n\n\n\n<li>Ejecuci\u00f3n de acuerdos.<\/li>\n\n\n\n<li>Respuesta a reclamaciones de que cualquier publicaci\u00f3n u otro contenido viola derechos de terceros.<\/li>\n\n\n\n<li>Resoluci\u00f3n de disputas.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"\">No recopilaremos categor\u00edas adicionales de Datos personales ni utilizaremos los Datos personales que recopilamos para fines sustancialmente diferentes, no relacionados o incompatibles sin notificarle de acuerdo con la secci\u00f3n <a href=\"https:\/\/hallow.com\/privacy-policy\/%23changes-to-privacy-policy\">\u00abCambios a esta Pol\u00edtica de privacidad\u00bb<\/a> m\u00e1s adelante. Si usted es residente de California, tenga en cuenta que solo utilizamos o divulgamos su informaci\u00f3n personal confidencial para los fines establecidos en la secci\u00f3n 7027(m) de las regulaciones de la CCPA y no recopilamos ni procesamos informaci\u00f3n personal confidencial con el prop\u00f3sito de inferir ninguna caracter\u00edstica sobre usted.<\/p>\n\n\n\n<p class=\"\"><strong>3. Divulgaci\u00f3n de datos<\/strong><\/p>\n\n\n\n<p class=\"\">Revelamos sus Datos personales a las categor\u00edas de proveedores de servicios y otras partes enumeradas en esta secci\u00f3n. Para obtener m\u00e1s informaci\u00f3n, consulte las secciones espec\u00edficas de cada estado m\u00e1s adelante.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Proveedores de servicios<\/strong>\u00a0Estas partes nos ayudan a proporcionar los Servicios o a realizar funciones comerciales en nuestro nombre. Incluyen:\n<ul class=\"wp-block-list\">\n<li>Proveedores de alojamiento, tecnolog\u00eda y comunicaciones.<\/li>\n\n\n\n<li>Proveedores de soporte y servicio al cliente.<\/li>\n\n\n\n<li>Proveedores de cumplimiento y entrega de productos.<\/li>\n\n\n\n<li>Procesadores de pagos\n<ul class=\"wp-block-list\">\n<li>Cuando usted realiza una compra a trav\u00e9s de nuestros Servicios (no se aplica a una compra realizada a trav\u00e9s de una Tienda de aplicaciones de terceros), nuestro socio de procesamiento de pagos (por ejemplo, Stripe) recopila su informaci\u00f3n de tarjeta de pago proporcionada voluntariamente y necesaria para procesar su pago. Consulte los t\u00e9rminos de servicio y la pol\u00edtica de privacidad del procesador de pagos para obtener informaci\u00f3n sobre el uso y almacenamiento que hace con sus Datos personales.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Socios publicitarios\u00a0<\/strong>Estas partes nos ayudan a comercializar nuestros servicios y a ofrecerle otras ofertas que pueden ser de su inter\u00e9s. Incluyen:\n<ul class=\"wp-block-list\">\n<li>Redes publicitarias.<\/li>\n\n\n\n<li>Proveedores de marketing.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Socios anal\u00edticos\u00a0<\/strong>Estas partes proporcionan an\u00e1lisis sobre el tr\u00e1fico web o el uso de los Servicios. Incluyen:\n<ul class=\"wp-block-list\">\n<li>Empresas que rastrean c\u00f3mo los usuarios interact\u00faan con los Servicios.<\/li>\n\n\n\n<li>Empresas que rastrean c\u00f3mo los usuarios encontraron o fueron referidos a los Servicios.\u00a0<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Socios de recaudaci\u00f3n de fondos <\/strong>Estos socios reciben donaciones de usted cuando usted elige participar en una campa\u00f1a de donaciones de Hallow. Incluyen:\n<ul class=\"wp-block-list\">\n<li>Organizaciones exentas de impuestos u otras organizaciones sin fines de lucro<\/li>\n\n\n\n<li>Iglesias y di\u00f3cesis.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Partes que usted autoriza, accede o autentica.<\/strong>\n<ul class=\"wp-block-list\">\n<li>Terceros a los que usted accede a trav\u00e9s de los Servicios<\/li>\n\n\n\n<li>Otros usuarios, incluyendo aquellos de su red Consulte la secci\u00f3n Comunidad de Hallow m\u00e1s adelante para obtener m\u00e1s informaci\u00f3n.\u00a0<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"\"><strong>Comunidad de Hallow&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"\">La funci\u00f3n Comunidad de Hallow permite a los usuarios orar con y por otros, encontrarse, conectarse y compartir contenido como una forma de enriquecer los procesos espirituales de los dem\u00e1s. Cuando usted comparte y se comunica utilizando la Aplicaci\u00f3n, usted elige qu\u00e9 comparte y la audiencia con la que lo comparte.&nbsp; &nbsp; &nbsp; Ciertas cuentas de Hollow, incluyendo cuentas de menores, pueden tener restringido el acceso y la participaci\u00f3n en algunas o todas las funciones de la Comunidad, incluyendo la funcionalidad de grupo, uso compartido y mensajer\u00eda descrita en esta secci\u00f3n. Si usted participa en la funci\u00f3n Comunidad,&nbsp; &nbsp; &nbsp; usted puede controlar su experiencia en la Comunidad personalizando su configuraci\u00f3n, incluyendo el grado en que otros usuarios pueden localizar su cuenta y el contenido que comparte. Por ejemplo, cuando usted publica una intenci\u00f3n o reflexi\u00f3n basadas en texto, puede optar por compartir ese contenido con su red en la Aplicaci\u00f3n. Tambi\u00e9n puede optar por permitir que su red vea cu\u00e1ndo usted realiza ciertas acciones dentro de la Aplicaci\u00f3n, como escuchar una sesi\u00f3n de oraci\u00f3n espec\u00edfica, y hacer que su perfil pueda ser buscado por otras personas en la comunidad de Hallow. Adem\u00e1s, cuando usted comenta la publicaci\u00f3n de otra persona o reacciona a su contenido, su comentario o reacci\u00f3n es visible para cualquier persona que pueda ver el contenido de la otra persona y esa persona puede cambiar la audiencia m\u00e1s tarde. El mismo nivel de opci\u00f3n existe dentro del contexto de grupo. Si usted elige participar en uno de nuestros grupos (como una parroquia de la que usted es miembro), puede optar por hacer que sus interacciones dentro del grupo sean visibles para otros miembros del grupo o el administrador del grupo relevante. Finalmente, cuando usted elige enviar mensajes directos para comunicarse con otros usuarios de Hallow, esos usuarios pueden ver el contenido que usted env\u00eda.&nbsp;<\/p>\n\n\n\n<p class=\"\">Recuerde que debe considerar qu\u00e9 comparte y con qui\u00e9n elige compartir, porque las personas que pueden ver su actividad dentro de nuestra Aplicaci\u00f3n pueden optar por compartirla con otros, incluyendo personas fuera de la audiencia con la que usted la comparti\u00f3 inicialmente.<\/p>\n\n\n\n<p class=\"\"><strong>Obligaciones legales<\/strong><\/p>\n\n\n\n<p class=\"\">Podemos revelar cualquier dato personal que recopilemos con terceros en relaci\u00f3n con cualquiera de las actividades establecidas en \u00abCumplimiento de los requisitos legales y cumplimiento de los t\u00e9rminos legales\u00bb en la secci\u00f3n \u00ab<a href=\"https:\/\/hallow.com\/privacy-policy\/%23purposes-for-collecting-personal-data\">Nuestros prop\u00f3sitos comerciales o empresariales para recopilar datos personales<\/a>\u00bb anterior.&nbsp;<\/p>\n\n\n\n<p class=\"\"><strong>Transferencias empresariales<\/strong><\/p>\n\n\n\n<p class=\"\">Todos sus Datos personales que recopilamos pueden transferirse a un tercero si nos sometemos a una fusi\u00f3n, adquisici\u00f3n, quiebra u otra transacci\u00f3n en la que ese tercero asuma el control de nuestra empresa (en su totalidad o en parte). Si ocurre uno de estos eventos, haremos esfuerzos razonables para notificarle antes (muy probablemente por correo electr\u00f3nico) que su informaci\u00f3n est\u00e9 sujeta a diferentes pol\u00edticas y pr\u00e1cticas de privacidad o seguridad.<\/p>\n\n\n\n<p class=\"\"><strong>Datos que no son datos personales<\/strong><\/p>\n\n\n\n<p class=\"\">Podemos crear datos agregados, no identificados o an\u00f3nimos a partir de los Datos personales que recopilamos, incluso eliminando informaci\u00f3n que haga que los datos sean personalmente identificables para un usuario en particular. Podemos utilizar dichos datos agregados, no identificados o an\u00f3nimos y divulgarlos a terceros para nuestros fines comerciales leg\u00edtimos, inclusive para analizar, desarrollar y mejorar los Servicios y promocionar nuestro negocio, siempre que no divulguemos dichos datos de una manera que pueda identificarlo. &nbsp;<\/p>\n\n\n\n<p class=\"\"><strong>4. Seguridad y retenci\u00f3n de datos<\/strong><\/p>\n\n\n\n<p class=\"\">Buscamos proteger sus Datos personales contra el acceso, el uso y la divulgaci\u00f3n no autorizados utilizando medidas de seguridad f\u00edsicas, t\u00e9cnicas, organizativas y administrativas adecuadas en funci\u00f3n del tipo de Datos personales y de c\u00f3mo procesamos esos datos.&nbsp;<strong>Utilizamos cifrado est\u00e1ndar de la industria para proteger sus datos y ciframos adem\u00e1s los Datos personales confidenciales privados de una manera dise\u00f1ada para garantizar que solo usted y aquellas personas con las que usted elija compartirlos puedan verlos de forma no cifrada.&nbsp;<\/strong>Tambi\u00e9n le pedimos que nos ayude a proteger sus datos seleccionando y protegiendo adecuadamente su contrase\u00f1a y\/u otro mecanismo de inicio de sesi\u00f3n; limitando el acceso a su computadora o dispositivo y navegador; y cerrando sesi\u00f3n despu\u00e9s de que usted haya terminado de acceder a su cuenta. Aunque trabajamos para proteger la seguridad de su cuenta y otros datos que tenemos en nuestros registros, tenga en cuenta que ning\u00fan m\u00e9todo de transmisi\u00f3n de datos a trav\u00e9s de Internet o de almacenamiento de datos es completamente seguro.<\/p>\n\n\n\n<p class=\"\">Retenemos sus Datos personales mientras usted tenga una cuenta abierta con nosotros o seg\u00fan sea necesario para proporcionarle nuestros Servicios. En algunos casos, conservamos Datos personales durante m\u00e1s tiempo, si hacerlo es necesario para cumplir con nuestras obligaciones legales o comerciales, resolver disputas o cobrar tarifas adeudadas, o si lo requieren las leyes, normas o regulaciones aplicables. Tambi\u00e9n podemos conservar informaci\u00f3n de forma an\u00f3nima, no identificada y agregada, de modo que la informaci\u00f3n no lo identifique personalmente.&nbsp; &nbsp; &nbsp;<\/p>\n\n\n\n<p class=\"\">&nbsp;&nbsp; &nbsp; No divulgamos los Datos personales de ning\u00fan Ni\u00f1o menor de la edad protegida a ning\u00fan Socio anal\u00edtico o publicitario. Para obtener una descripci\u00f3n general de los Proveedores de servicios utilizados para tratar Datos personales, consulte la <a href=\"https:\/\/hallow.com\/privacy-policy\/%23personal-data\">Secci\u00f3n 2<\/a>. Si su cuenta se elimina, eliminamos sus Datos personales en un plazo de 30 d\u00edas.&nbsp; &nbsp; &nbsp;<\/p>\n\n\n\n<p class=\"\"><strong>5. Datos personales de menores<\/strong><\/p>\n\n\n\n<p class=\"\">La Ley de Protecci\u00f3n de la Privacidad en L\u00ednea de los Ni\u00f1os (\u00abCOPPA\u00bb) requiere que los proveedores de servicios en l\u00ednea obtengan el consentimiento de los padres antes de recopilar a sabiendas informaci\u00f3n personal (como se define en COPPA) en l\u00ednea de ni\u00f1os menores de 13 a\u00f1os (en cada caso, un \u00abNi\u00f1o menor de la edad protegida\u00bb).&nbsp; Otras leyes de privacidad aplicables, como el RGPD y&nbsp; &nbsp; &nbsp; ciertas leyes estatales de los Estados Unidos, tambi\u00e9n pueden regular la recopilaci\u00f3n de Datos personales de menores de cierta edad (cada uno, un \u00abMenor\u00bb).<\/p>\n\n\n\n<p class=\"\"><strong>Cuentas individuales<\/strong><\/p>\n\n\n\n<p class=\"\">Esta secci\u00f3n describe nuestras pr\u00e1cticas con respecto a los Datos personales de menores, excepto por lo establecido en la secci\u00f3n \u00abCuentas escolares\u00bb m\u00e1s adelante.<\/p>\n\n\n\n<p class=\"\">No recopilamos ni solicitamos a sabiendas informaci\u00f3n personal de un&nbsp; &nbsp; &nbsp; ni\u00f1o menor de la edad protegida sin obtener la autorizaci\u00f3n verificable del padre o tutor de ese ni\u00f1o (\u00abautorizaci\u00f3n parental\u00bb), con excepci\u00f3n de la cantidad limitada de informaci\u00f3n personal que necesitamos recopilar para obtener la autorizaci\u00f3n parental (\u00abinformaci\u00f3n necesaria\u00bb). Hasta que hayamos recibido la autorizaci\u00f3n parental, solo utilizaremos la informaci\u00f3n necesaria con el objetivo de obtener la autorizaci\u00f3n parental. Si usted es un Ni\u00f1o menor de la edad &nbsp; &nbsp; protegida, no intente enviarnos ning\u00fan Dato personal sobre usted antes de que obtengamos el Consentimiento parental, excepto la informaci\u00f3n requerida en el contexto del proceso de Consentimiento parental. Si usted cree que un Ni\u00f1o menor de la edad protegida nos ha proporcionado Datos personales (m\u00e1s all\u00e1 de la informaci\u00f3n requerida) sin que nosotros hayamos obtenido el consentimiento de los padres, cont\u00e1ctenos a <a href=\"mailto:support@hallow.com\">support@hallow.com<\/a>. No condicionamos la participaci\u00f3n en nuestros Servicios a la revelaci\u00f3n de m\u00e1s datos personales de&nbsp; &nbsp; &nbsp; menores de los razonablemente necesarios para esa participaci\u00f3n, y no conservamos datos personales de menores m\u00e1s tiempo que el razonablemente necesario para cumplir con el prop\u00f3sito para el que fueron revelados. Para obtener informaci\u00f3n adicional sobre nuestras pr\u00e1cticas de retenci\u00f3n de datos relacionadas con informaci\u00f3n personal de un Ni\u00f1o menor de la edad protegida, consulte la secci\u00f3n \u00ab<a href=\"https:\/\/hallow.com\/privacy-policy\/%23data-security-and-retention\">Seguridad y retenci\u00f3n de datos<\/a>\u00bb anterior.<\/p>\n\n\n\n<p class=\"\">Si usted es padre, madre o tutor de un usuario de nuestros Servicios que es un Ni\u00f1o menor de la edad protegida, usted puede comunicarse con nosotros en cualquier momento para solicitar que (a) dejemos de recopilar Datos personales de dicho usuario, (b) lo ayudemos a eliminar cualquier dato personal ya recopilado de dicho usuario (aunque tenga en cuenta que podemos retener informaci\u00f3n de forma an\u00f3nima, no identificada o agregada cuando esa informaci\u00f3n no identificar\u00eda personalmente a dicho usuario), o (c) dejemos de revelar datos personales recopilados de dicho usuario a terceros, pero sigamos permitiendo la recopilaci\u00f3n y el uso de datos personales recopilados de dicho usuario en relaci\u00f3n con los Servicios.&nbsp;<\/p>\n\n\n\n<p class=\"\">Para ayudar a los padres y tutores a proteger y administrar la privacidad de los Menores en l\u00ednea, Hallow ofrece a los padres y tutores la capacidad de permitir el acceso de un Menor a los Servicios a trav\u00e9s de un \u00abPerfil infantil\u00bb asociado con la cuenta de dichos padres o tutores (dicha cuenta, la \u00abCuenta de padres\u00bb).&nbsp;<\/p>\n\n\n\n<p class=\"\">Si usted es un Ni\u00f1o menor de la edad &nbsp; &nbsp; protegida, o si usted est\u00e1 utilizando los Servicios a trav\u00e9s de un Perfil infantil asociado con una Cuenta parental, su padre, madre o tutor puede ver toda la informaci\u00f3n dentro de o asociada con su cuenta de KAY, incluidos, sin limitaci\u00f3n, todas las categor\u00edas de Datos personales como se describen anteriormente, comunic\u00e1ndose con nosotros a la direcci\u00f3n <a href=\"mailto:support@hallow.com\">support@hallow.com<\/a>. Ciertas caracter\u00edsticas o funcionalidades en los Servicios pueden estar restringidas o no disponibles para los Menores o cualquier otro usuario que acceda a los Servicios a trav\u00e9s de un Perfil infantil.<\/p>\n\n\n\n<p class=\"\">Para mayor claridad, no recopilamos, mantenemos, utilizamos ni compartimos a sabiendas ning\u00fan dato personal de ning\u00fan usuario que sea un Ni\u00f1o menor de la edad protegida m\u00e1s all\u00e1 de lo necesario para fines autorizados, o seg\u00fan lo autorizado por el usuario o sus padres o tutores legales. En ning\u00fan caso vendemos ning\u00fan dato personal de usuarios que sean Ni\u00f1os menores de la edad &nbsp; &nbsp; protegida. Tampoco utilizamos ni divulgamos a sabiendas Datos personales de ning\u00fan&nbsp; &nbsp; &nbsp; menor para la orientaci\u00f3n por comportamiento de los anuncios.<\/p>\n\n\n\n<p class=\"\"><strong>Cuentas escolares<\/strong><\/p>\n\n\n\n<p class=\"\">En relaci\u00f3n con una Cuenta empresarial de una escuela o instituci\u00f3n educativa (cada una, una \u00abCuenta escolar\u00bb), podemos recopilar Datos personales sobre menores, incluyendo ni\u00f1os menores de la edad protegida. Como parte de estas asociaciones, su escuela o instituci\u00f3n educativa puede asumir la responsabilidad de recopilar el consentimiento apropiado (incluido el Consentimiento de los Padres cuando sea necesario) para la recopilaci\u00f3n, el uso, el procesamiento y la divulgaci\u00f3n de Datos personales (incluida la informaci\u00f3n requerida) sobre dichos Menores por parte de Huntington.<\/p>\n\n\n\n<p class=\"\"><strong>6.&nbsp; &nbsp; &nbsp; Derechos de privacidad estatales de los Estados Unidos<\/strong><\/p>\n\n\n\n<p class=\"\">Si usted reside en ciertos estados de los Estados Unidos, como California, Colorado, Connecticut, Delaware, Indiana, Iowa, Kentucky, Maryland, Minnesota, Montana, Nebraska, Nuevo Hampshire, Nueva Jersey, Oreg\u00f3n, Rhode Island, Tennessee, Texas, Utah y Virginia, es posible que tenga ciertos derechos (como se describen m\u00e1s adelante) dependiendo de su estado de residencia. Consulte la secci\u00f3n \u00ab<a href=\"https:\/\/hallow.com\/privacy-policy\/%23exercising-your-rights-under-u.s.-state-privacy-laws\">Ejercicio de sus derechos bajo las leyes de privacidad estatales de los Estados Unidos<\/a>\u00bb m\u00e1s adelante para obtener instrucciones sobre c\u00f3mo ejercer estos derechos. Tenga en cuenta que sus derechos pueden estar sujetos a ciertas condiciones o excepciones de acuerdo con las leyes de privacidad estatales aplicables de los Estados Unidos.<\/p>\n\n\n\n<p class=\"\">Si tiene alguna pregunta sobre esta secci\u00f3n o si alguno de los siguientes derechos se aplica a usted, cont\u00e1ctenos a la direcci\u00f3n <a href=\"mailto:support@hallow.com\">support@hallow.com<\/a>&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Acceso<\/em>: Usted puede tener derecho a solicitar confirmaci\u00f3n o acceso a los Datos personales que procesamos sobre usted. Tambi\u00e9n puede solicitar que le enviemos una copia de sus Datos personales. Si usted es residente de Oregon, tambi\u00e9n tiene derecho a solicitar una lista de terceros espec\u00edficos, que no sean personas f\u00edsicas, a los que les hayamos divulgado sus Datos personales.<\/li>\n\n\n\n<li>Eliminaci\u00f3n: Usted puede tener derecho a solicitar que eliminemos los Datos personales que hemos recopilado sobre usted.\u00a0<\/li>\n\n\n\n<li>Correcci\u00f3n: Usted puede tener derecho a solicitar que corrijamos cualquier dato personal inexacto que hayamos recopilado sobre usted.\u00a0<\/li>\n\n\n\n<li>Formato: Usted puede tener derecho a solicitar una copia de sus Datos personales en un formato legible por m\u00e1quina, en la medida en que sea t\u00e9cnicamente factible.<\/li>\n<\/ul>\n\n\n\n<p class=\"\"><em>Exclusi\u00f3n voluntaria y aceptaci\u00f3n voluntaria de intercambio de datos personales<\/em><\/p>\n\n\n\n<p class=\"\">Como se describe en nuestra Pol\u00edtica de cookies, hemos incorporado cookies de ciertos terceros en nuestros Servicios. Estas cookies permiten a esos terceros recibir informaci\u00f3n sobre su actividad en nuestros Servicios que est\u00e1 asociada con su navegador o dispositivo. Esos terceros pueden utilizar esos datos para mostrarle anuncios relevantes en otros sitios web que usted visite. Aunque definimos datos de venta como el intercambio de datos a cambio de una compensaci\u00f3n monetaria o no monetaria, seg\u00fan algunas leyes de privacidad estatales de los Estados Unidos, compartir sus datos a trav\u00e9s de cookies de terceros para publicidad en l\u00ednea puede considerarse una \u00abventa\u00bb o \u00abintercambio de informaci\u00f3n\u00bb. Usted siempre tiene control total sobre si estas tecnolog\u00edas funcionan en sus dispositivos, incluso para desactivar la publicidad dirigida.&nbsp; Puede desactivarlas por completo haciendo clic en el enlace <a href=\"https:\/\/hallow.com\/privacy-policy\/\">\u00ab<\/a><a href=\"https:\/\/hallow.com\/privacy-policy\/%23cookie-manager\">Administrar<\/a><a href=\"https:\/\/hallow.com\/privacy-policy\/\"> cookies\u00bb<\/a> en nuestro sitio web.&nbsp;<\/p>\n\n\n\n<p class=\"\">&nbsp;&nbsp; &nbsp; No vendemos ni compartimos, con nuestro conocimiento, los Datos personales de menores.&nbsp;&nbsp; &nbsp; &nbsp;<\/p>\n\n\n\n<p class=\"\"><em>Procesamiento de datos personales confidenciales&nbsp;<\/em><\/p>\n\n\n\n<p class=\"\">Seg\u00fan sea necesario, podemos comunicarnos con usted para que nos proporcione Datos personales, como se describe anteriormente en la secci\u00f3n \u00ab<a href=\"https:\/\/hallow.com\/privacy-policy\/%23categories-of-personal-data-we-collect\">Categor\u00edas de datos personales que recopilamos<\/a>\u00ab, que pueden considerarse \u00abconfidenciales\u00bb seg\u00fan ciertas leyes de privacidad estatales de los Estados Unidos (\u00abDatos personales confidenciales\u00bb).&nbsp;<\/p>\n\n\n\n<p class=\"\">Dependiendo de su estado de residencia, usted puede tener el derecho de optar por participar, el derecho de optar por excluirse o, si usted es residente de California, el derecho de limitar nuestro uso de sus Datos personales confidenciales siguiendo las instrucciones de la secci\u00f3n \u00ab<a href=\"https:\/\/hallow.com\/privacy-policy\/%23exercising-your-rights-under-u.s.-state-privacy-laws\">Ejercicio de sus derechos bajo las leyes de privacidad estatales de los Estados<\/a> Unidos\u00bb.<\/p>\n\n\n\n<p class=\"\"><em>Toma de decisiones automatizada<\/em><\/p>\n\n\n\n<p class=\"\">No procesamos sus Datos personales para la \u00abelaboraci\u00f3n de perfiles\u00bb como se define en ciertas leyes de privacidad estatales de los Estados Unidos (el uso de tecnolog\u00eda de toma de decisiones o el procesamiento de datos en apoyo de decisiones que producen efectos legales o similares para usted). Si se toma una decisi\u00f3n automatizada (por ejemplo, una interacci\u00f3n en la comunidad que fue marcada autom\u00e1ticamente por profanidad o que infringe nuestras Pautas de la comunidad), usted puede apelar la decisi\u00f3n comunic\u00e1ndose a la direcci\u00f3n support@hallow.com.&nbsp;<\/p>\n\n\n\n<p class=\"\"><em>No lo discriminaremos por ejercer sus derechos en virtud de las leyes de privacidad estatales de los Estados Unidos<\/em><\/p>\n\n\n\n<p class=\"\">No lo discriminaremos por ejercer sus derechos en virtud de las leyes de privacidad aplicables. No le negaremos nuestros productos o servicios, no le cobraremos precios o tarifas diferentes ni le proporcionaremos productos de menor calidad si usted ejerce sus derechos en virtud de las leyes de privacidad aplicables.&nbsp;<\/p>\n\n\n\n<p class=\"\"><em>Otros derechos de privacidad espec\u00edficos del estado<\/em><\/p>\n\n\n\n<p class=\"\">En virtud de las secciones 1798.83-1798.84 del C\u00f3digo Civil de California, los residentes de California tienen derecho a comunicarse con nosotros para restringir la divulgaci\u00f3n de Datos personales a terceros solo a las divulgaciones necesarias para que los Servicios funcionen (por ejemplo, eliminar las categor\u00edas de datos de publicidad y cookies como se definen anteriormente); Para enviar una solicitud de este tipo, comun\u00edquese con nosotros a la direcci\u00f3n support@hallow.com.&nbsp;<\/p>\n\n\n\n<p class=\"\">Su navegador puede ofrecerle una opci\u00f3n \u00abNo rastrear\u00bb, que le permite indicarle a los operadores de sitios web y aplicaciones web y servicios que usted no desea que dichos operadores rastreen algunas de sus actividades en l\u00ednea a lo largo del tiempo y en diferentes sitios web. Dado que la mayor\u00eda de los navegadores no tienen funcionalidad para admitir solicitudes de no rastrear, nuestros Servicios no admiten estas solicitudes en este momento. Para obtener m\u00e1s informaci\u00f3n sobre \u00abNo rastrear\u00bb, puede visitar www.allaboutdnt.com.<\/p>\n\n\n\n<p class=\"\">Aunque no vendemos sus Datos personales, estamos obligados a decirle aqu\u00ed que si usted es residente de Nevada, tiene derecho a optar por no participar en la venta de ciertos Datos personales a terceros, como&nbsp; &nbsp; &nbsp; se define en el Cap\u00edtulo 603A de los Estatutos Revisados de Nevada.&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n\n\n\n<p class=\"\"><strong>&nbsp;&nbsp; &nbsp; 7. Ejercicio de sus derechos bajo las leyes de privacidad estatales de los Estados Unidos<\/strong><\/p>\n\n\n\n<p class=\"\">Para ejercer los derechos descritos en esta Pol\u00edtica de privacidad, usted o su Agente autorizado (si corresponde y como se define m\u00e1s adelante) deben enviarnos una solicitud que (1) proporcione informaci\u00f3n suficiente (por ejemplo, credenciales de inicio de sesi\u00f3n de su cuenta) para permitirnos verificar que usted es la persona sobre la que hemos recopilado Datos personales y (2) describa su solicitud con suficiente detalle para permitirnos comprenderla, evaluar y responderla. Cada solicitud que cumpla con estos dos criterios se considera una \u00abSolicitud v\u00e1lida\u00bb. Es posible que no respondamos a solicitudes que no cumplan con estos criterios. Solo utilizaremos los Datos personales proporcionados en una Solicitud v\u00e1lida para verificar su identidad y completar su solicitud. Usted no necesita una cuenta para enviar una solicitud v\u00e1lida.<\/p>\n\n\n\n<p class=\"\">Nos esforzaremos para responder a su Solicitud v\u00e1lida en el per\u00edodo de tiempo requerido por la ley aplicable. No le cobraremos un cargo por hacer una Solicitud v\u00e1lida a menos que su Solicitud v\u00e1lida sea excesiva, repetitiva o manifiestamente infundada. Si determinamos que su Solicitud v\u00e1lida justifica un cargo, le notificaremos sobre el cargo y le explicaremos esa decisi\u00f3n antes de completar su solicitud.<\/p>\n\n\n\n<p class=\"\">Usted puede enviar una Solicitud v\u00e1lida envi\u00e1ndonos un correo electr\u00f3nico a: <a href=\"mailto:support@hallow.com\">support@hallow.com<\/a> con el asunto \u00abSolicitud de derechos de datos\u00bb.<\/p>\n\n\n\n<p class=\"\">&nbsp;&nbsp; &nbsp; Si usted es residente de California, Colorado, Connecticut, Delaware, Maryland, Minnesota, Montana, Nebraska, Nuevo Hampshire, Nueva Jersey, Oreg\u00f3n, Rhode Island o Texas, tambi\u00e9n puede autorizar a un agente (un \u00abAgente autorizado\u00bb) a ejercer sus derechos en su nombre. Para hacer esto, usted debe proporcionarle a su Agente autorizado un permiso por escrito para ejercer sus derechos en su nombre y nosotros podemos solicitar una copia de esta autorizaci\u00f3n por escrito a su Agente autorizado cuando \u00e9ste haga una solicitud en su nombre.<\/p>\n\n\n\n<p class=\"\"><em>Apelar una denegaci\u00f3n<\/em><\/p>\n\n\n\n<p class=\"\">Si usted es residente de Colorado, Connecticut, Delaware, Indiana, Iowa, Kentucky, Maryland, Minnesota, Montana, Nebraska, Nuevo Hampshire, Nueva Jersey, Oreg\u00f3n, Rhode Island, Tennessee, Texas o Virginia y nos negamos a tomar medidas sobre su solicitud dentro de un per\u00edodo de tiempo razonable despu\u00e9s de recibir su solicitud de acuerdo con esta secci\u00f3n, usted puede apelar nuestra decisi\u00f3n. En dicha apelaci\u00f3n, usted debe (1) proporcionar informaci\u00f3n suficiente para permitirnos verificar que usted es la persona a quien se refiere la solicitud original y para identificar la solicitud original y (2) proporcionar una descripci\u00f3n de la base de su apelaci\u00f3n. Tenga en cuenta que su apelaci\u00f3n estar\u00e1 sujeta a los derechos y obligaciones que se le otorgan en virtud de las Leyes de privacidad estatales (seg\u00fan corresponda). Responderemos a su apelaci\u00f3n dentro del per\u00edodo de tiempo requerido por la ley aplicable. Puede enviar una Solicitud verificada para apelaci\u00f3n mediante los siguientes m\u00e9todos:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Env\u00edenos un correo electr\u00f3nico a: support@hallow.com (el t\u00edtulo debe incluir \u00abApelaci\u00f3n [ESTADO DE RESIDENCIA]\u00bb)<\/li>\n\n\n\n<li>Ll\u00e1menos al: +1 (773) 900-7145<\/li>\n<\/ul>\n\n\n\n<p class=\"\">Si denegamos su apelaci\u00f3n, usted tiene derecho a comunicarse con el Fiscal General de su estado, incluso a trav\u00e9s de los siguientes enlaces: <a href=\"http:\/\/www.coag.gov\/resources\/colorado-privacy-act\/\">Colorado<\/a>, <a href=\"http:\/\/www.portal.ct.gov\/AG\/Sections\/Privacy\/The-Privacy-and-Data-Security-Department\">Connecticut<\/a>, <a href=\"https:\/\/attorneygeneral.delaware.gov\/fraud\/cmu\/complaint\/\">Delaware<\/a>, <a href=\"https:\/\/www.in.gov\/attorneygeneral\/consumer-protection-division\/file-a-complaint\/\">Indiana<\/a>, <a href=\"https:\/\/www.iowaattorneygeneral.gov\/for-consumers\/file-a-consumer-complaint\">Iowa<\/a>, <a href=\"https:\/\/www.ag.ky.gov\/Resources\/Consumer-Resources\/Consumers\/Pages\/Consumer-Complaints.aspx\">Kentucky<\/a>, <a href=\"https:\/\/www.marylandattorneygeneral.gov\/Pages\/CPD\/Complaint.aspx\">Maryland<\/a>, <a href=\"https:\/\/www.ag.state.mn.us\/office\/complaint.asp\">Minnesota<\/a>, <a href=\"https:\/\/dojmt.gov\/office-of-consumer-protection\/consumer-complaints\/\">Montana<\/a>, <a href=\"https:\/\/www.nebraska.gov\/apps-ago-complaints\/\">Nebraska<\/a>, <a href=\"https:\/\/www.doj.nh.gov\/citizens\/consumer-protection-antitrust-bureau\/consumer-complaints\">Nuevo Hampshire<\/a>, <a href=\"https:\/\/www.njconsumeraffairs.gov\/\">Nueva Jersey<\/a>, <a href=\"https:\/\/www.doj.state.or.us\/consumer-protection\/\">Oreg\u00f3n<\/a>, <a href=\"https:\/\/www.tn.gov\/attorneygeneral\/working-for-tennessee\/consumer-affairs.html\">Tennessee<\/a>, <a href=\"https:\/\/www.texasattorneygeneral.gov\/consumer-protection\/file-consumer-complaint\">Texas<\/a> y <a href=\"http:\/\/www.oag.state.va.us\/consumer-protection\/index.php\/file-a-complaint\">Virginia<\/a>.&nbsp;<\/p>\n\n\n\n<p class=\"\"><strong>&nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; 8. Derechos de los interesados de la Uni\u00f3n Europea y del Reino Unido<\/strong><\/p>\n\n\n\n<p class=\"\"><strong>Residentes de la UE y el Reino Unido<\/strong><\/p>\n\n\n\n<p class=\"\">Si usted es residente de la Uni\u00f3n Europea (\u00abUE\u00bb), el Reino Unido (\u00abReino Unido\u00bb), Lichtenstein, Noruega o Islandia, es posible que tenga derechos adicionales en virtud del Reglamento General de Protecci\u00f3n de Datos de la UE y la versi\u00f3n del RGPD mantenida en la ley del Reino Unido (conjuntamente, el \u00abRGPD\u00bb) con respecto a sus Datos personales, como se describe m\u00e1s adelante. &nbsp;<\/p>\n\n\n\n<p class=\"\">Para esta secci\u00f3n, utilizamos los t\u00e9rminos \u00abDatos personales\u00bb y \u00abprocesamiento\u00bb tal como se definen en el RGPD, pero \u00abDatos personales\u00bb generalmente se refiere a informaci\u00f3n que se puede utilizar para identificar individualmente a una persona, y el \u00abprocesamiento\u00bb generalmente cubre acciones que se pueden realizar en relaci\u00f3n con datos como la recopilaci\u00f3n, el uso, el almacenamiento y la divulgaci\u00f3n. Hallow ser\u00e1 el controlador de sus Datos personales procesados en relaci\u00f3n con los Servicios.<\/p>\n\n\n\n<p class=\"\">Si hay alg\u00fan conflicto entre esta secci\u00f3n y cualquier otra disposici\u00f3n de esta Pol\u00edtica de privacidad, la pol\u00edtica o la parte que sea m\u00e1s protectora para los Datos personales prevalecer\u00e1 en lo que ata\u00f1e a dicho conflicto. Si tiene alguna pregunta sobre esta secci\u00f3n o si alguno de los siguientes \u00edtems se aplica a usted, cont\u00e1ctenos a la direcci\u00f3n <a href=\"mailto:support@hallow.com\">support@hallow.com<\/a>.<\/p>\n\n\n\n<p class=\"\"><strong>Datos personales que recopilamos<\/strong><\/p>\n\n\n\n<p class=\"\">La secci\u00f3n anterior <a href=\"https:\/\/hallow.com\/privacy-policy\/%23categories-of-personal-data-we-collect\">\u201cCategor\u00edas de datos personales que recopilamos\u201d<\/a> detalla los Datos personales que recopilamos.<\/p>\n\n\n\n<p class=\"\"><strong>Uso de datos personales y motivos del procesamiento<\/strong><\/p>\n\n\n\n<p class=\"\">La secci\u00f3n anterior <a href=\"https:\/\/hallow.com\/privacy-policy\/%23purposes-for-collecting-personal-data\">\u00abNuestros prop\u00f3sitos comerciales o empresariales para recopilar datos personales\u00bb<\/a> explica c\u00f3mo utilizamos sus Datos personales.<\/p>\n\n\n\n<p class=\"\">Solo procesaremos sus Datos personales si tenemos una base legal para hacerlo. Las bases legales para el procesamiento incluyen el consentimiento, la necesidad contractual y nuestros \u00abintereses leg\u00edtimos\u00bb o el inter\u00e9s leg\u00edtimo de otros, como se describe con m\u00e1s detalle m\u00e1s adelante.<\/p>\n\n\n\n<p class=\"\">Necesidad contractual: Procesamos las siguientes categor\u00edas de Datos personales como una cuesti\u00f3n de \u00abnecesidad contractual\u00bb, lo que significa que necesitamos procesar los datos para operar en virtud de nuestros T\u00e9rminos de servicio con usted, lo que nos permite brindarle los Servicios. Cuando procesamos datos debido a una necesidad contractual, el hecho de no proporcionar dichos Datos personales har\u00e1 que usted no pueda utilizar la totalidad o parte de los Servicios que requieren dichos datos.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Datos de perfil o de contacto<\/li>\n\n\n\n<li>Datos personales confidenciales privados (solo contrase\u00f1as)<\/li>\n\n\n\n<li>Datos de pago<\/li>\n\n\n\n<li>Datos de recaudaci\u00f3n de fondos<\/li>\n\n\n\n<li>Otra informaci\u00f3n de identificaci\u00f3n que usted elige proporcionar voluntariamente\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"\">Inter\u00e9s leg\u00edtimo: Procesamos las siguientes categor\u00edas de Datos personales cuando creemos que tienen un inter\u00e9s leg\u00edtimo (seg\u00fan lo definido por el RGPD):&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>An\u00e1lisis de aplicaciones<\/li>\n\n\n\n<li>Datos de dispositivo\/IP<\/li>\n\n\n\n<li>An\u00e1lisis web<\/li>\n\n\n\n<li>Datos de publicidad<\/li>\n\n\n\n<li>Datos demogr\u00e1ficos de los consumidores\u00a0<\/li>\n\n\n\n<li>Datos de geolocalizaci\u00f3n<\/li>\n\n\n\n<li>Cookies y an\u00e1lisis de sitios web<\/li>\n\n\n\n<li>Datos de salud<\/li>\n\n\n\n<li>Informaci\u00f3n de contacto para ventas de cuentas empresariales<\/li>\n\n\n\n<li>Datos de recaudaci\u00f3n de fondos<\/li>\n\n\n\n<li>Otra informaci\u00f3n de identificaci\u00f3n que usted elige proporcionar voluntariamente\u00a0<\/li>\n\n\n\n<li>Tambi\u00e9n podemos desidentificar o anonimizar Datos personales para promover nuestros intereses leg\u00edtimos.\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"\">Ejemplos de estos intereses leg\u00edtimos incluyen (como se describe con m\u00e1s detalle anteriormente):<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Proveer, personalizar y mejorar los Servicios.<\/li>\n\n\n\n<li>Comercializaci\u00f3n de los Servicios.<\/li>\n\n\n\n<li>Mantener correspondencia con usted.<\/li>\n\n\n\n<li>Cumplimiento de los requisitos legales y aplicaci\u00f3n de los t\u00e9rminos legales<\/li>\n\n\n\n<li>Completar transacciones corporativas<\/li>\n<\/ul>\n\n\n\n<p class=\"\">Consentimiento: En algunos casos, procesamos Datos personales en funci\u00f3n del consentimiento (como cuando procesamos sus Datos personales confidenciales privados) que usted nos otorga expresamente en el momento en que recopilamos dichos datos. Cuando procesamos Datos personales en funci\u00f3n de su consentimiento, esto se le indicar\u00e1 expresamente en el momento de la recopilaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"\">Otros motivos de procesamiento: Ocasionalmente, tambi\u00e9n es posible que necesitemos procesar Datos personales para cumplir con una obligaci\u00f3n legal, si es necesario para proteger los intereses vitales suyos o de otros interesados, o si es necesario para una tarea realizada en pos del inter\u00e9s p\u00fablico.<\/p>\n\n\n\n<p class=\"\"><strong>Compartir datos personales<\/strong><\/p>\n\n\n\n<p class=\"\">La secci\u00f3n anterior <a href=\"https:\/\/hallow.com\/privacy-policy\/%23data-sharing\">\u00abDivulgaci\u00f3n de datos\u00bb<\/a> detalla c\u00f3mo compartimos sus Datos personales con terceros.&nbsp;<\/p>\n\n\n\n<p class=\"\"><strong>Derechos de los interesados de la UE<\/strong><\/p>\n\n\n\n<p class=\"\">Usted tiene ciertos derechos con respecto a sus Datos personales, incluyendo los establecidos m\u00e1s adelante. Para enviar una solicitud relacionada con estos derechos, visite <a href=\"https:\/\/hallow.gdprlocal.com\/eu\">https:\/\/hallow.gdprlocal.com\/eu<\/a> y complete el formulario proporcionado. Tenga en cuenta que en algunas circunstancias es posible que no podamos cumplir completamente con su solicitud, por ejemplo, si es fr\u00edvola o extremadamente poco pr\u00e1ctica, si pone en peligro los derechos de otros o si no es requerido por la ley, pero en esas circunstancias, a\u00fan responderemos para notificarle sobre dicha decisi\u00f3n. En algunos casos, tambi\u00e9n es posible que necesitemos que usted nos proporcione informaci\u00f3n adicional, que puede incluir Datos personales, si es necesario para verificar su identidad y la naturaleza de su solicitud. &nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Acceso<\/strong>: Usted puede solicitar m\u00e1s informaci\u00f3n sobre los Datos personales que tenemos sobre usted y solicitar una copia de dichos Datos personales. Tambi\u00e9n puede acceder a algunos de sus Datos personales iniciando sesi\u00f3n en su cuenta.<\/li>\n\n\n\n<li><strong>Rectificaci\u00f3n<\/strong>: Si usted cree que cualquier dato personal que tengamos sobre usted es inexacto o incompleto, usted puede solicitar que corrijamos o complementemos esos datos. Tambi\u00e9n puede corregir parte de esta informaci\u00f3n directamente iniciando sesi\u00f3n en su cuenta.<\/li>\n\n\n\n<li><strong>Borrado<\/strong>: Usted puede solicitar que borremos la totalidad o parte de sus datos personales de nuestros sistemas. \u00a0<\/li>\n\n\n\n<li><strong>Retiro del consentimiento<\/strong>: Si procesamos sus Datos personales en funci\u00f3n de su consentimiento (como se indica en el momento de la recopilaci\u00f3n de dichos datos), usted tiene derecho a retirar su consentimiento en cualquier momento. Sin embargo, tenga en cuenta que si usted ejerce este derecho, es posible que deba proporcionar su consentimiento expreso caso por caso para el uso o la divulgaci\u00f3n de algunos de sus Datos personales, si dicho uso o divulgaci\u00f3n es necesario para permitirle utilizar algunos o todos nuestros Servicios.\u00a0<\/li>\n\n\n\n<li><strong>Portabilidad<\/strong>: usted puede solicitar una copia de sus Datos personales en un formato legible por m\u00e1quina. Tambi\u00e9n puede solicitar que transmitamos los datos a otro controlador cuando sea t\u00e9cnicamente factible.<\/li>\n\n\n\n<li><strong>Oposici\u00f3n<\/strong>: Usted puede comunicarse con nosotros para informarnos que usted se opone al uso o la divulgaci\u00f3n posterior de sus Datos personales para ciertos fines, como con fines de marketing directo.\u00a0<\/li>\n\n\n\n<li><strong>Restricci\u00f3n del procesamiento<\/strong>: Usted puede solicitarnos que restrinjamos el procesamiento adicional de sus Datos personales.<\/li>\n\n\n\n<li><strong>Derecho a presentar una queja<\/strong>: Usted tiene derecho a presentar una queja sobre las pr\u00e1cticas de Hallow con respecto a sus Datos personales ante la autoridad supervisora de su pa\u00eds o estado miembro de la UE. Hay una lista de las autoridades supervisoras disponible aqu\u00ed: <a href=\"https:\/\/edpb.europa.eu\/about-edpb\/board\/members_en\">https:\/\/edpb.europa.eu\/about-edpb\/board\/members_en<\/a>.<\/li>\n<\/ul>\n\n\n\n<p class=\"\"><strong>Transferencias de datos personales<\/strong><\/p>\n\n\n\n<p class=\"\">Hallow tiene su sede y los Servicios est\u00e1n alojados y operados en los Estados Unidos (\u00abEE. UU.\u00bb) a trav\u00e9s de Hallow y su proveedor de servicios. Si usted no reside en los Estados Unidos, las leyes de los Estados Unidos pueden ser diferentes de las leyes en el lugar en que usted reside. Al utilizar los Servicios, usted reconoce que cualquier dato personal sobre usted, independientemente de si fue proporcionado por usted u obtenido de un tercero, se proporciona a Hallow en los Estados Unidos y estar\u00e1 alojado en servidores de los Estados Unidos, y usted autoriza a Hallow a transferir, almacenar y procesar su informaci\u00f3n en los Estados Unidos y posiblemente en otros pa\u00edses.&nbsp;<\/p>\n\n\n\n<p class=\"\"><strong>&nbsp;&nbsp; &nbsp; 9. Derechos de los interesados en Brasil<\/strong><\/p>\n\n\n\n<p class=\"\">El art\u00edculo 18 de la Ley General de Protecci\u00f3n de Datos Personales (\u00abLGPD\u00bb) establece los siguientes derechos para los usuarios ubicados en Brasil:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Confirmaci\u00f3n de la existencia de procesamiento;<\/li>\n\n\n\n<li>Acceso a los datos;<\/li>\n\n\n\n<li>Correcci\u00f3n de datos incompletos, inexactos o obsoletos;<\/li>\n\n\n\n<li>Anonimizaci\u00f3n, bloqueo o eliminaci\u00f3n de datos innecesarios, excesivos o procesados en violaci\u00f3n de las disposiciones de la LGPD;<\/li>\n\n\n\n<li>Portabilidad de los datos a otro proveedor de servicios o productos, a solicitud expresa, de acuerdo con las regulaciones locales de Brasil y sujeta al secreto comercial e industrial;<\/li>\n\n\n\n<li>Eliminaci\u00f3n de datos personales tratados con el consentimiento del interesado, excepto en los casos previstos en el art\u00edculo 16 de la LGPD;<\/li>\n\n\n\n<li>Informaci\u00f3n sobre entidades p\u00fablicas y privadas con las que el controlador ha compartido datos;<\/li>\n\n\n\n<li>Informaci\u00f3n sobre la posibilidad de no dar el consentimiento y sobre las consecuencias de dicha denegaci\u00f3n;<\/li>\n\n\n\n<li>Revocaci\u00f3n de consentimiento, de conformidad con el art\u00edculo 8, apartado 5, de la LGPD.<\/li>\n<\/ul>\n\n\n\n<p class=\"\">Usted puede enviar una Solicitud v\u00e1lida (consulte la secci\u00f3n Ejercicio de sus derechos anterior para obtener m\u00e1s detalles) envi\u00e1ndonos un correo electr\u00f3nico a <a href=\"mailto:support@hallow.com\">support@hallow.com<\/a> con el asunto \u00abSolicitud de derechos de datos de LGPD\u00bb. Tenga en cuenta que, en algunas circunstancias, es posible que no podamos cumplir completamente con su solicitud, por ejemplo si es fr\u00edvola o extremadamente poco pr\u00e1ctica, si pone en peligro los derechos de otros o si no es requerido por la ley, pero en esas circunstancias, a\u00fan responderemos para notificarle sobre dicha decisi\u00f3n.<\/p>\n\n\n\n<p class=\"\"><strong>&nbsp;&nbsp; &nbsp; 10. Cambios a esta Pol\u00edtica de privacidad<\/strong><\/p>\n\n\n\n<p class=\"\">Intentamos mejorar constantemente nuestros Servicios, por lo que es posible que necesitemos cambiar esta Pol\u00edtica de privacidad de vez en cuando, pero le notificaremos sobre cualquier cambio sustancial publicando un aviso en el sitio web de Hallow, envi\u00e1ndole un correo electr\u00f3nico y\/o por otros medios. Tenga en cuenta que, si usted ha optado por no recibir correos electr\u00f3nicos de notificaciones legales de nosotros (o no nos ha proporcionado su direcci\u00f3n de correo electr\u00f3nico), esas notificaciones legales a\u00fan regir\u00e1n su uso de los Servicios y usted a\u00fan es responsable de leerlas y comprenderlas. Si usted utiliza los Servicios despu\u00e9s de que se hayan publicado cambios en la Pol\u00edtica de privacidad, eso significa que usted acepta todos los cambios. El uso de la informaci\u00f3n que recopilamos est\u00e1 sujeto a la Pol\u00edtica de privacidad vigente en el momento en que se recopil\u00f3 dicha informaci\u00f3n.<\/p>\n\n\n\n<p class=\"\"><strong>&nbsp;&nbsp; &nbsp; 11. Informaci\u00f3n de contacto<\/strong><\/p>\n\n\n\n<p class=\"\">Si tiene alguna pregunta o comentario sobre esta Pol\u00edtica de privacidad, las formas en que recopilamos y utilizamos sus Datos personales o sus opciones y derechos con respecto a dicha recopilaci\u00f3n y uso, no dude en comunicarse con nosotros en:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/hallow.com\/\">https:\/\/hallow.com<\/a><\/li>\n\n\n\n<li><a href=\"mailto:support@hallow.com\">soporte@hallow.com<\/a><\/li>\n\n\n\n<li>980 N Michigan Ave, Ste 1090 #273579, Chicago, IL 60611<\/li>\n\n\n\n<li>+1 (773) 900-7145<\/li>\n<\/ul>\n\n\n\n<p class=\"\">Si usted se encuentra en la UE o el Reino Unido, puede usar la siguiente informaci\u00f3n para contactar a nuestro Representante de miembros con sede en la UE o el Reino Unido:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Representante de miembro de la UE:<\/strong><\/td><td><strong>Representante de miembros del Reino Unido:<\/strong><\/td><\/tr><tr><td>Instant EU GDPR Representative Ltd Adam Brogden contacto@gdprlocal.com + 353 15 549 700 https:\/\/hallow.gdprlocal.com\/eu<br>INSTANT EU GDPR REPRESENTATIVE LIMITED Office 2 12A&nbsp; Lower Main Street, Lucan Co.&nbsp; Dubl\u00edn K78 X5P8, Irlanda<\/td><td>GDPR Local Ltd Adam Brogden contacto@gdprlocal.com + 441 772 217 800 https:\/\/hallow.gdprlocal.com\/uk<br>GDPR Local Ltd&nbsp; 1st Floor, Front Suite&nbsp; 27-29 North Street Brighton, England BN1 1EB<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>NOTA: Esta versi\u00f3n de la Pol\u00edtica de privacidad se public\u00f3 inicialmente el 9 de julio de 2026 y entra en vigor el 17 de julio de 2026. Se puede acceder a las versiones anteriores de nuestra Pol\u00edtica de privacidad aqu\u00ed. En Hallow damos gran importancia a la protecci\u00f3n de los datos y la privacidad. Esta &hellip; <a href=\"https:\/\/hallow.com\/es\/politica-de-privacidad\/\">Continued<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"views\/legal.blade.php","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-26709","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.3 (Yoast SEO v25.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pol\u00edtica de Privacidad &#8211; Hallow<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hallow.com\/es\/politica-de-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Privacidad\" \/>\n<meta property=\"og:description\" content=\"NOTA: Esta versi\u00f3n de la Pol\u00edtica de privacidad se public\u00f3 inicialmente el 9 de julio de 2026 y entra en vigor el 17 de julio de 2026. Se puede acceder a las versiones anteriores de nuestra Pol\u00edtica de privacidad aqu\u00ed. En Hallow damos gran importancia a la protecci\u00f3n de los datos y la privacidad. Esta &hellip; Continued\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hallow.com\/es\/politica-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Hallow\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/hallowapp\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T19:40:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hallow.com\/wp-content\/uploads\/2022\/04\/Branch.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@hallowapp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hallow.com\/es\/politica-de-privacidad\/\",\"url\":\"https:\/\/hallow.com\/es\/politica-de-privacidad\/\",\"name\":\"Pol\u00edtica de Privacidad &#8211; Hallow\",\"isPartOf\":{\"@id\":\"https:\/\/hallow.com\/es\/#website\"},\"datePublished\":\"2019-03-26T15:43:40+00:00\",\"dateModified\":\"2026-07-11T19:40:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hallow.com\/es\/politica-de-privacidad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hallow.com\/es\/politica-de-privacidad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hallow.com\/es\/politica-de-privacidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hallow.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hallow.com\/es\/#website\",\"url\":\"https:\/\/hallow.com\/es\/\",\"name\":\"Hallow\",\"description\":\"Catholic Prayer and Meditation App\",\"publisher\":{\"@id\":\"https:\/\/hallow.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hallow.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hallow.com\/es\/#organization\",\"name\":\"Hallow\",\"url\":\"https:\/\/hallow.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/hallow.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hallow.com\/wp-content\/uploads\/2019\/04\/Purple-Logo.png\",\"contentUrl\":\"https:\/\/hallow.com\/wp-content\/uploads\/2019\/04\/Purple-Logo.png\",\"width\":1470,\"height\":292,\"caption\":\"Hallow\"},\"image\":{\"@id\":\"https:\/\/hallow.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/hallowapp\",\"https:\/\/x.com\/hallowapp\",\"https:\/\/instagram.com\/hallowapp\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Privacidad &#8211; Hallow","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hallow.com\/es\/politica-de-privacidad\/","og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de Privacidad","og_description":"NOTA: Esta versi\u00f3n de la Pol\u00edtica de privacidad se public\u00f3 inicialmente el 9 de julio de 2026 y entra en vigor el 17 de julio de 2026. Se puede acceder a las versiones anteriores de nuestra Pol\u00edtica de privacidad aqu\u00ed. En Hallow damos gran importancia a la protecci\u00f3n de los datos y la privacidad. Esta &hellip; Continued","og_url":"https:\/\/hallow.com\/es\/politica-de-privacidad\/","og_site_name":"Hallow","article_publisher":"https:\/\/facebook.com\/hallowapp","article_modified_time":"2026-07-11T19:40:50+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/hallow.com\/wp-content\/uploads\/2022\/04\/Branch.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@hallowapp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hallow.com\/es\/politica-de-privacidad\/","url":"https:\/\/hallow.com\/es\/politica-de-privacidad\/","name":"Pol\u00edtica de Privacidad &#8211; Hallow","isPartOf":{"@id":"https:\/\/hallow.com\/es\/#website"},"datePublished":"2019-03-26T15:43:40+00:00","dateModified":"2026-07-11T19:40:50+00:00","breadcrumb":{"@id":"https:\/\/hallow.com\/es\/politica-de-privacidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hallow.com\/es\/politica-de-privacidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hallow.com\/es\/politica-de-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hallow.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Privacidad"}]},{"@type":"WebSite","@id":"https:\/\/hallow.com\/es\/#website","url":"https:\/\/hallow.com\/es\/","name":"Hallow","description":"Catholic Prayer and Meditation App","publisher":{"@id":"https:\/\/hallow.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hallow.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hallow.com\/es\/#organization","name":"Hallow","url":"https:\/\/hallow.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hallow.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hallow.com\/wp-content\/uploads\/2019\/04\/Purple-Logo.png","contentUrl":"https:\/\/hallow.com\/wp-content\/uploads\/2019\/04\/Purple-Logo.png","width":1470,"height":292,"caption":"Hallow"},"image":{"@id":"https:\/\/hallow.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/hallowapp","https:\/\/x.com\/hallowapp","https:\/\/instagram.com\/hallowapp"]}]}},"_links":{"self":[{"href":"https:\/\/hallow.com\/es\/wp-json\/wp\/v2\/pages\/26709"}],"collection":[{"href":"https:\/\/hallow.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hallow.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hallow.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hallow.com\/es\/wp-json\/wp\/v2\/comments?post=26709"}],"version-history":[{"count":9,"href":"https:\/\/hallow.com\/es\/wp-json\/wp\/v2\/pages\/26709\/revisions"}],"predecessor-version":[{"id":118026,"href":"https:\/\/hallow.com\/es\/wp-json\/wp\/v2\/pages\/26709\/revisions\/118026"}],"wp:attachment":[{"href":"https:\/\/hallow.com\/es\/wp-json\/wp\/v2\/media?parent=26709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}